{"id":3171,"date":"2017-03-18T00:24:10","date_gmt":"2017-03-18T00:24:10","guid":{"rendered":"http:\/\/ojoscuriosos.com\/?p=3171"},"modified":"2017-03-18T00:24:10","modified_gmt":"2017-03-18T00:24:10","slug":"unas","status":"publish","type":"post","link":"https:\/\/megatandil.com.ar\/ojoscuriosos\/unas\/","title":{"rendered":"Nuestras U\u00f1as"},"content":{"rendered":"<h2><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/08\/980000.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3176\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/08\/980000.jpg\" alt=\"980000\" width=\"507\" height=\"337\" \/><\/a><span style=\"color: #000080;\">El <strong>Ayurveda<\/strong> es un antiguo sistema de medicina tradicional, cuyo origen est\u00e1 en la <strong>India<\/strong> y tienen una antig\u00fcedad superior a los dos mil a\u00f1os.<\/span><\/h2>\n<p>Ya en esos textos se mencionan una extra\u00f1as <em>ranuras longitudinales y transversales en las u\u00f1as de los seres humanos<\/em>. \u00a0Seg\u00fan se afirma, cada una de estas l\u00edneas tienen causas diferentes, ya que las primeras no tienen mayor importancia, pero las transversales pueden ser el origen de alg\u00fan trastorno de salud.<\/p>\n<p>Estas ranuras horizontales se deben a que unas semanas antes, <em><strong>aproximadamente un\u00a0 mes y medio atr\u00e1s,<\/strong><\/em> se ha producido una interrupci\u00f3n en el crecimiento de la u\u00f1a, lo cual es un indicio claro de alg\u00fan asunto org\u00e1nico a\u00fan latente.<\/p>\n<p>A simple vista se pueden observar una fin\u00edsimas ranuras verticales que se forman cuando la u\u00f1a crece. Como all\u00ed se genera el material que compone la u\u00f1a, \u00e9sta suele tener m\u00e1s grosor en ese punto y adquiere una estructura de l\u00edneas longitudinales. \u00a0Si las partes finas se desgastan producto de un mal trato, ya sea con detergentes, solventes o quitaesmaltes, el perfil ondulado se refuerza a\u00fan m\u00e1s, pero no es m\u00e1s que un problema est\u00e9tico.<\/p>\n<p>Las l\u00edneas y<strong> surcos horizontales<\/strong> revelan sin embargo, un trastorno o incluso\u00a0 una interrupci\u00f3n total del crecimiento a causa de una queratinizaci\u00f3n insuficiente. Esto se puede deber por ejemplo, a una enfermedad infecciosa como la escarlatina, tifus, pulmon\u00eda, hepatitis o gripe fuerte, entre otras.<\/p>\n<p>Si se presentan ranuras y l\u00edneas en forma repetida, pueden ser reveladoras de enfermedades agudas. Hay causas muy comunes como por ejemplo, trastornos de metabolismo o del equilibrio hormonal, o tambi\u00e9n enfermedades de la piel o eccemas.<\/p>\n<p><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/08\/00090909.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3175\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/08\/00090909.jpg\" alt=\"00090909\" width=\"275\" height=\"183\" \/><\/a> <a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/08\/00009.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3174\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/08\/00009.jpeg\" alt=\"00009\" width=\"678\" height=\"353\" \/><\/a> <a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/08\/000.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-3173\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/08\/000.jpg\" alt=\"000\" width=\"600\" height=\"250\" \/><\/a><\/p>\n<p>En un enfermo de psoriasis, las u\u00f1as pueden presentar peque\u00f1as abolladuras con forma de punto. Incluso las peque\u00f1as <strong>manchitas blancas<\/strong> que a veces aparecen son una especie de informe que algo no anda del todo bien. La zona donde se produce el material que forma la u\u00f1a es la matriz situada en su ra\u00edz, que convierte las c\u00e9lulas cut\u00e1neas en duras escamas c\u00f3rneas, cuyo material es en gran parte <strong>queratina<\/strong>. Este complejo sistema de s\u00edntesis puede verse alterado a causa de peque\u00f1as heridas o leves trastornos de alimentaci\u00f3n o por la influencia de medicamentos.\u00a0 En esos casos la u\u00f1a crece con algunas anomal\u00edas. O se implantan part\u00edculas de calcio en la u\u00f1a para rellenar peque\u00f1os huecos o quedan atrapadas burbujas de aire en la c\u00f3rnea. All\u00ed entonces se dejan ver las manchitas blancas.<\/p>\n<p>Muchas veces esto es inocuo, pero otras veces pueden alertar sobre falta de minerales o vitaminas, problemas hep\u00e1ticos, defectos card\u00edacos y hasta problemas ps\u00edquicos.\u00a0 El tiempo de aparici\u00f3n del problema puede medirse f\u00e1cil. Se mide la distancia de la mancha desde el crecimiento de la ra\u00edz y se calcula el tiempo transcurrido en funci\u00f3n de la velocidad de crecimiento que suele ser de dos a tres mil\u00edmetros por mes.<\/p>\n<p><strong>Verdad que ya te est\u00e1s mirando las u\u00f1as?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<form id=\"vozme_form_e7d259957e016064fa312dc3d1e61825\" method=\"post\" name=\"vozme_form_e7d259957e016064fa312dc3d1e61825\" target=\"e7d259957e016064fa312dc3d1e61825\" action=\"http:\/\/vozme.com\/text2voice.php\"><input name=\"text\" type=\"hidden\" value=\"Nuestras U\u00f1as. El Ayurveda es un antiguo sistema de medicina tradicional, cuyo origen est\u00e1 en la India y tienen una antig\u00fcedad superior a los dos mil a\u00f1os.\nYa en esos textos se mencionan una extra\u00f1as ranuras longitudinales y transversales en las u\u00f1as de los seres humanos. \u00a0Seg\u00fan se afirma, cada una de estas l\u00edneas tienen causas diferentes, ya que las primeras no tienen mayor importancia, pero las transversales pueden ser el origen de alg\u00fan trastorno de salud.\nEstas ranuras horizontales se deben a que unas semanas antes, aproximadamente un\u00a0 mes y medio atr\u00e1s, se ha producido una interrupci\u00f3n en el crecimiento de la u\u00f1a, lo cual es un indicio claro de alg\u00fan asunto org\u00e1nico a\u00fan latente.\nA simple vista se pueden observar una fin\u00edsimas ranuras verticales que se forman cuando la u\u00f1a crece. Como all\u00ed se genera el material que compone la u\u00f1a, \u00e9sta suele tener m\u00e1s grosor en ese punto y adquiere una estructura de l\u00edneas longitudinales. \u00a0Si las partes finas se desgastan producto de un mal trato, ya sea con detergentes, solventes o quitaesmaltes, el perfil ondulado se refuerza a\u00fan m\u00e1s, pero no es m\u00e1s que un problema est\u00e9tico.\nLas l\u00edneas y surcos horizontales revelan sin embargo, un trastorno o incluso\u00a0 una interrupci\u00f3n total del crecimiento a causa de una queratinizaci\u00f3n insuficiente. Esto se puede deber por ejemplo, a una enfermedad infecciosa como la escarlatina, tifus, pulmon\u00eda, hepatitis o gripe fuerte, entre otras.\nSi se presentan ranuras y l\u00edneas en forma repetida, pueden ser reveladoras de enfermedades agudas. Hay causas muy comunes como por ejemplo, trastornos de metabolismo o del equilibrio hormonal, o tambi\u00e9n enfermedades de la piel o eccemas.\n  \nEn un enfermo de psoriasis, las u\u00f1as pueden presentar peque\u00f1as abolladuras con forma de punto. Incluso las peque\u00f1as manchitas blancas que a veces aparecen son una especie de informe que algo no anda del todo bien. La zona donde se produce el material que forma la u\u00f1a es la matriz situada en su ra\u00edz, que convierte las c\u00e9lulas cut\u00e1neas en duras escamas c\u00f3rneas, cuyo material es en gran parte queratina. Este complejo sistema de s\u00edntesis puede verse alterado a causa de peque\u00f1as heridas o leves trastornos de alimentaci\u00f3n o por la influencia de medicamentos.\u00a0 En esos casos la u\u00f1a crece con algunas anomal\u00edas. O se implantan part\u00edculas de calcio en la u\u00f1a para rellenar peque\u00f1os huecos o quedan atrapadas burbujas de aire en la c\u00f3rnea. All\u00ed entonces se dejan ver las manchitas blancas.\nMuchas veces esto es inocuo, pero otras veces pueden alertar sobre falta de minerales o vitaminas, problemas hep\u00e1ticos, defectos card\u00edacos y hasta problemas ps\u00edquicos.\u00a0 El tiempo de aparici\u00f3n del problema puede medirse f\u00e1cil. Se mide la distancia de la mancha desde el crecimiento de la ra\u00edz y se calcula el tiempo transcurrido en funci\u00f3n de la velocidad de crecimiento que suele ser de dos a tres mil\u00edmetros por mes.\nVerdad que ya te est\u00e1s mirando las u\u00f1as?\n&nbsp;\n\" \/><input name=\"lang\" type=\"hidden\" value=\"es\" \/><input name=\"gn\" type=\"hidden\" value=\"ml\" \/><input type=\"hidden\" id=\"interface\" name=\"interface\" value=\"full\" \/>\n\t\t\t<div style=\"text-align:left;\">\n\t\t\t\n\t\t\t\t<input style=\"float:left;\" type=\"image\" width=\"40\" height=\"40\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/plugins\/vozme\/img\/megaphone40x40w.gif\" alt=\"Escucha este post\" onclick=\"window.open('', 'e7d259957e016064fa312dc3d1e61825', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes');\">\n\t\t\t\t<div style=\"margin-left:48px; text-align:left;\"><a style=\"font-size:12px;\" href=\"javascript:void(0);\" onclick=\"window.open('', 'e7d259957e016064fa312dc3d1e61825', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes'); document.getElementById('vozme_form_e7d259957e016064fa312dc3d1e61825').submit();\">Escucha<br\/>este post<\/a><\/div>\n\t\t\t<\/div><\/form>","protected":false},"excerpt":{"rendered":"<p>El Ayurveda es un antiguo sistema de medicina tradicional, cuyo origen est\u00e1 en la India y tienen una antig\u00fcedad superior a los dos mil a\u00f1os. Ya en esos textos se mencionan una extra\u00f1as ranuras longitudinales y transversales en las u\u00f1as de los seres humanos. \u00a0Seg\u00fan se afirma, cada una de estas l\u00edneas tienen causas diferentes, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6740,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,1],"tags":[285,286,287,288],"class_list":["post-3171","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cuerpo-humano","category-sin-categoria","tag-manchas","tag-ranuras","tag-salud","tag-unas","czr-hentry"],"_links":{"self":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/3171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/comments?post=3171"}],"version-history":[{"count":0,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/3171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media\/6740"}],"wp:attachment":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media?parent=3171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/categories?post=3171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/tags?post=3171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}