{"id":473,"date":"2017-04-30T00:58:04","date_gmt":"2017-04-30T00:58:04","guid":{"rendered":"http:\/\/ojoscuriosos.com\/?p=473"},"modified":"2017-04-30T00:58:04","modified_gmt":"2017-04-30T00:58:04","slug":"el-misterio-de-la-cumbre","status":"publish","type":"post","link":"https:\/\/megatandil.com.ar\/ojoscuriosos\/el-misterio-de-la-cumbre\/","title":{"rendered":"El Misterio del Everest"},"content":{"rendered":"<h2><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/himalaya_everest_primera_ascension_invernal_1980_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-5018\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/himalaya_everest_primera_ascension_invernal_1980_4.jpg\" alt=\"himalaya_everest_primera_ascension_invernal_1980_4\" width=\"720\" height=\"479\" \/><\/a>El <strong>29 de mayo de 1953<\/strong>, la cumbre del <strong>Everet,<\/strong> el monte m\u00e1s alto del mundo, fue conquistada por <strong>Edmund Hillary<\/strong>, quien pas\u00f3 a la historia por ser el primer hombre que pudo llegar a la cima del gigante rocoso.<\/h2>\n<p>Sin embargo no hay una sola foto que lo muestre a Hillary en ese lugar.<\/p>\n<p>Se lleg\u00f3 a sospechar que el verdadero h\u00e9roe fue el sherpa <strong>Tenzing,<\/strong> uno de los hombres que lo acompa\u00f1aba en la expedici\u00f3n y que iba varios metros adelante. Incluso sobre este nativo del lugar cay\u00f3 la acusaci\u00f3n de haber aceptado sobornos para callar la verdad de la historia.\u00a0 El argumento de Hillary con respecto a la ausencia de la foto que certificar\u00eda su haza\u00f1a, es que estaba m\u00e1s interesado en retratar el entorno que retratarse en la cima del mundo. Algo poco cre\u00edble, pero dentro de las posibilidades.<a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/sir-edmund-hillary-wireless-radio_49925_600x450.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-5017\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/sir-edmund-hillary-wireless-radio_49925_600x450.jpg\" alt=\"sir-edmund-hillary-wireless-radio_49925_600x450\" width=\"600\" height=\"450\" \/><\/a> <a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/images-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-5016\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/images-6.jpg\" alt=\"images (6)\" width=\"259\" height=\"194\" \/><\/a><\/p>\n<p>Pero eso no es todo. En junio de 1924, es decir casi treinta a\u00f1os antes, un joven ingl\u00e9s llamado <strong>George Mallory<\/strong> inici\u00f3 el asalto final a la cumbre del Everest, luego de dos intentos fallidos en 1921 y 1922. Quiso la suerte que falleciera en el camino junto a un compa\u00f1ero de apellido Irvine. Pero la duda hasta el d\u00eda de hoy es saber si muri\u00f3 subiendo o si la muerte lo sorprendi\u00f3 bajando luego de hacer cima, lo cual anular\u00eda la supuesta haza\u00f1a de Hillary.<\/p>\n<p>El cuerpo de Mallory fue rescatado reci\u00e9n en 1999, con casi todas sus pertenencias y a muy pocos metros de la cima. Aunque no se sabe cual fue el motivo de su muerte, la posici\u00f3n del cuerpo era extra\u00f1a. Con los brazos abiertos, sin guantes y boca abajo, parec\u00eda que hubiese tropezado en la nieve y no hubiese podido levantarse. Las pruebas realizadas parecen indicar que el accidente fue bajando, o sea que existe la firme posibilidad de que este hombre haya sido el primero en hacer cima en la cumbre m\u00e1s alta del mundo. Junto a todas estas conjeturas existe en alg\u00fan lugar de la monta\u00f1a, algo que ser\u00eda la prueba contundente de tal haza\u00f1a: la c\u00e1mara Kodak que llevaba este monta\u00f1ista y que a\u00fan no ha sido hallada.<a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/Hillary_and_tenzing.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-5015\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/Hillary_and_tenzing.jpg\" alt=\"Hillary_and_tenzing\" width=\"828\" height=\"494\" \/><\/a> <a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/389950-3x2-940x627.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-5014\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/05\/389950-3x2-940x627.jpg\" alt=\"389950-3x2-940x627\" width=\"940\" height=\"627\" \/><\/a><\/p>\n<p><span style=\"color: #000000;\">La sequedad del aire a esa altura y el frio extremo podr\u00eda haber mantenido intacta la pel\u00edcula. No hay dudas que de <a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/edmund_hillary_1448986c.jpg\"><span style=\"color: #000000;\">encontrase este documento, tambi\u00e9n podr\u00eda estar la foto que documente que Mallory le gan\u00f3 a Hillary por varios a\u00f1os. Como resumen podr\u00eda decirse que ante tantas dudas, solo una foto podr\u00eda aclarar tanta oscuridad. <\/span><\/a><\/span><\/p>\n<h4><span style=\"color: #000000;\"><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/edmund_hillary_1448986c.jpg\"><span style=\"color: #000000;\"><strong>Pero hasta hoy, esa foto no existe en ninguno de los casos y eso hace que la historia no oficial sobre la haza\u00f1a de hacer cumbre, siga siendo un gran misterio.<\/strong><\/span><\/a><\/span><\/h4>\n<p><span style=\"text-decoration: underline;\">\u00a0<\/span><\/p>\n<figure id=\"attachment_478\" aria-describedby=\"caption-attachment-478\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/images-101.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-478\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/images-101-150x150.jpg\" alt=\"George Mallory y su esposa Ruth\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-478\" class=\"wp-caption-text\">George Mallory y su esposa Ruth<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_477\" aria-describedby=\"caption-attachment-477\" style=\"width: 150px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-477\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/images-91-150x150.jpg\" alt=\"Edmund Hillary\" width=\"150\" height=\"150\" \/><figcaption id=\"caption-attachment-477\" class=\"wp-caption-text\">Edmund Hillary<\/figcaption><\/figure>\n<p><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/images-91.jpg\">\u00a0<\/a><\/p>\n<figure id=\"attachment_476\" aria-describedby=\"caption-attachment-476\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/edmund_hillary_1448986c.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-476\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/edmund_hillary_1448986c-150x150.jpg\" alt=\"Grupo de Hillary\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-476\" class=\"wp-caption-text\">Grupo de Hillary<\/figcaption><\/figure>\n<figure id=\"attachment_475\" aria-describedby=\"caption-attachment-475\" style=\"width: 150px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/aa-in-the-alps.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-475\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/aa-in-the-alps-150x150.jpg\" alt=\"Mallory ascendiendo\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-475\" class=\"wp-caption-text\">Mallory ascendiendo<\/figcaption><\/figure>\n<p><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/aa-base-camp-colour.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-474\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/aa-base-camp-colour-150x150.jpg\" alt=\"aa base camp colour\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<form id=\"vozme_form_a560fbab14c44079b45474319354f21d\" method=\"post\" name=\"vozme_form_a560fbab14c44079b45474319354f21d\" target=\"a560fbab14c44079b45474319354f21d\" action=\"http:\/\/vozme.com\/text2voice.php\"><input name=\"text\" type=\"hidden\" value=\"El Misterio del Everest. El 29 de mayo de 1953, la cumbre del Everet, el monte m\u00e1s alto del mundo, fue conquistada por Edmund Hillary, quien pas\u00f3 a la historia por ser el primer hombre que pudo llegar a la cima del gigante rocoso.\nSin embargo no hay una sola foto que lo muestre a Hillary en ese lugar.\nSe lleg\u00f3 a sospechar que el verdadero h\u00e9roe fue el sherpa Tenzing, uno de los hombres que lo acompa\u00f1aba en la expedici\u00f3n y que iba varios metros adelante. Incluso sobre este nativo del lugar cay\u00f3 la acusaci\u00f3n de haber aceptado sobornos para callar la verdad de la historia.\u00a0 El argumento de Hillary con respecto a la ausencia de la foto que certificar\u00eda su haza\u00f1a, es que estaba m\u00e1s interesado en retratar el entorno que retratarse en la cima del mundo. Algo poco cre\u00edble, pero dentro de las posibilidades. \nPero eso no es todo. En junio de 1924, es decir casi treinta a\u00f1os antes, un joven ingl\u00e9s llamado George Mallory inici\u00f3 el asalto final a la cumbre del Everest, luego de dos intentos fallidos en 1921 y 1922. Quiso la suerte que falleciera en el camino junto a un compa\u00f1ero de apellido Irvine. Pero la duda hasta el d\u00eda de hoy es saber si muri\u00f3 subiendo o si la muerte lo sorprendi\u00f3 bajando luego de hacer cima, lo cual anular\u00eda la supuesta haza\u00f1a de Hillary.\nEl cuerpo de Mallory fue rescatado reci\u00e9n en 1999, con casi todas sus pertenencias y a muy pocos metros de la cima. Aunque no se sabe cual fue el motivo de su muerte, la posici\u00f3n del cuerpo era extra\u00f1a. Con los brazos abiertos, sin guantes y boca abajo, parec\u00eda que hubiese tropezado en la nieve y no hubiese podido levantarse. Las pruebas realizadas parecen indicar que el accidente fue bajando, o sea que existe la firme posibilidad de que este hombre haya sido el primero en hacer cima en la cumbre m\u00e1s alta del mundo. Junto a todas estas conjeturas existe en alg\u00fan lugar de la monta\u00f1a, algo que ser\u00eda la prueba contundente de tal haza\u00f1a: la c\u00e1mara Kodak que llevaba este monta\u00f1ista y que a\u00fan no ha sido hallada. \nLa sequedad del aire a esa altura y el frio extremo podr\u00eda haber mantenido intacta la pel\u00edcula. No hay dudas que de encontrase este documento, tambi\u00e9n podr\u00eda estar la foto que documente que Mallory le gan\u00f3 a Hillary por varios a\u00f1os. Como resumen podr\u00eda decirse que ante tantas dudas, solo una foto podr\u00eda aclarar tanta oscuridad. \nPero hasta hoy, esa foto no existe en ninguno de los casos y eso hace que la historia no oficial sobre la haza\u00f1a de hacer cumbre, siga siendo un gran misterio.\n\u00a0\n[caption id=&quot;attachment_478&quot; align=&quot;alignleft&quot; width=&quot;150&quot;] George Mallory y su esposa Ruth[\/caption]\n&nbsp;\n[caption id=&quot;attachment_477&quot; align=&quot;alignleft&quot; width=&quot;150&quot;] Edmund Hillary[\/caption]\n\u00a0\n[caption id=&quot;attachment_476&quot; align=&quot;alignleft&quot; width=&quot;150&quot;] Grupo de Hillary[\/caption]\n[caption id=&quot;attachment_475&quot; align=&quot;alignleft&quot; width=&quot;150&quot;] Mallory ascendiendo[\/caption]\n\n\" \/><input name=\"lang\" type=\"hidden\" value=\"es\" \/><input name=\"gn\" type=\"hidden\" value=\"ml\" \/><input type=\"hidden\" id=\"interface\" name=\"interface\" value=\"full\" \/>\n\t\t\t<div style=\"text-align:left;\">\n\t\t\t\n\t\t\t\t<input style=\"float:left;\" type=\"image\" width=\"40\" height=\"40\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/plugins\/vozme\/img\/megaphone40x40w.gif\" alt=\"Escucha este post\" onclick=\"window.open('', 'a560fbab14c44079b45474319354f21d', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes');\">\n\t\t\t\t<div style=\"margin-left:48px; text-align:left;\"><a style=\"font-size:12px;\" href=\"javascript:void(0);\" onclick=\"window.open('', 'a560fbab14c44079b45474319354f21d', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes'); document.getElementById('vozme_form_a560fbab14c44079b45474319354f21d').submit();\">Escucha<br\/>este post<\/a><\/div>\n\t\t\t<\/div><\/form>","protected":false},"excerpt":{"rendered":"<p>El 29 de mayo de 1953, la cumbre del Everet, el monte m\u00e1s alto del mundo, fue conquistada por Edmund Hillary, quien pas\u00f3 a la historia por ser el primer hombre que pudo llegar a la cima del gigante rocoso. Sin embargo no hay una sola foto que lo muestre a Hillary en ese lugar. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[214,11,3,16,13,1],"tags":[364,365,366,367,368],"class_list":["post-473","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte","category-historia","category-misterios","category-naturaleza","category-personajes","category-sin-categoria","tag-escalar","tag-everest","tag-hillary","tag-mallory","tag-monte","czr-hentry"],"_links":{"self":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/comments?post=473"}],"version-history":[{"count":0,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media\/482"}],"wp:attachment":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media?parent=473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/categories?post=473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/tags?post=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}