{"id":5221,"date":"2017-06-19T00:05:40","date_gmt":"2017-06-19T00:05:40","guid":{"rendered":"http:\/\/ojoscuriosos.com\/?p=5221"},"modified":"2017-06-19T00:05:40","modified_gmt":"2017-06-19T00:05:40","slug":"laciudaddelmiedo","status":"publish","type":"post","link":"https:\/\/megatandil.com.ar\/ojoscuriosos\/laciudaddelmiedo\/","title":{"rendered":"La Venecia del Miedo"},"content":{"rendered":"<h2><strong><a href=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/04\/Vista-de-Venecia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-5224\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/04\/Vista-de-Venecia.jpg\" alt=\"Vista-de-Venecia\" width=\"400\" height=\"300\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/04\/Vista-de-Venecia.jpg 400w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/04\/Vista-de-Venecia-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><span style=\"color: #008080;\">La fundaci\u00f3n de las ciudades, siempre est\u00e1 rodeada de hechos heroicos o situaciones forzadas, la mayor\u00eda de las cuales muchas veces se desconoce.\u00a0<\/span><\/strong><\/h2>\n<p>Una de esas historias es la que hoy despierta y evoca im\u00e1genes repletas de pasi\u00f3n.\u00a0 Porque tal vez una de las ciudades m\u00e1s curiosas y rom\u00e1nticas del mundo sea <strong>Venecia<\/strong> con sus g\u00f3ndolas que recorren suavemente las aguas del Gran Canal, con sus palacios del Renacimiento reflejados en las tranquilas aguas que todo lo rodean.\u00a0 Venecia es una postal moderna con sus plazas llenas de luz y de amor, junto a las palomas y gaviotas que revolotean pac\u00edficamente por sobre los puentes de arcada.<\/p>\n<p>Sin embargo no hubo nada rom\u00e1ntico en su fundaci\u00f3n. <em>Venecia naci\u00f3 de la desesperaci\u00f3n y el miedo<\/em>. Hace 1500 a\u00f1os atr\u00e1s, la actual Roma viv\u00eda tiempos complicados. El Imperio romano se estaba cayendo a pedazos y sufr\u00eda la embestida de feroces invasores b\u00e1rbaros del norte, que entraban en su territorio y asolaban lo que se interpusiera en su camino.<a href=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/04\/images-31.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-5223\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/04\/images-31.jpg\" alt=\"images (31)\" width=\"279\" height=\"181\" \/><\/a><\/p>\n<p>El \u00e1rea sobre la que actualmente se asienta Venecia, en aquel entonces consist\u00eda en un conjunto de isletas y peque\u00f1os pedazos de tierra sobre una laguna en forma de media luna, totalmente est\u00e9ril, cenagosa, maloliente y mugrienta.\u00a0 No hab\u00eda nada que tuviera a su favor, excepto que era una zona que brindaba, justamente por estas caracter\u00edsticas, cierta seguridad.<\/p>\n<p>En el <strong>a\u00f1o 452<\/strong>, cuando <strong>Atila<\/strong> y sus bravos hunos saquearon la ciudad de Aquilea en tierra firme, los habitantes huyeron a estos pantanos, salvando su pellejo. Un siglo m\u00e1s tarde, la invasi\u00f3n de los lombardos empuj\u00f3 a los aterrorizados pobladores de las ciudades, a buscar refugio en las isletas y as\u00ed fue que, entre desesperaci\u00f3n, miedo y experiencia, los reci\u00e9n llegados aprendieron r\u00e1pidamente a enfrentarse con un medio hostil pero seguro: un entorno acu\u00e1tico de dif\u00edcil subsistencia pero no imposible.\u00a0 Protegieron con estacas las isletas de lodo, construyeron palafitos y unieron las peque\u00f1as zonas sin agua entre s\u00ed rellenando los canales.<\/p>\n<p>Situada cerca del centro de la laguna, Venecia fue adquiriendo pujanza sobre las dem\u00e1s colonias menores y para el Siglo VIII era una rep\u00fablica aristocr\u00e1tica independiente con un gobernante electo, al que llamaban Dux.\u00a0 As\u00ed siguieron varios siglos de prosperidad econ\u00f3mica, pol\u00edtica y cultural. Nada hac\u00eda prever que pudiera surgir del lodo y la ci\u00e9naga, una pujante e incre\u00edble sociedad. Hacia fines del Siglo XVIII, en el archipi\u00e9lago de bancos de lodo e isletas que componen la hist\u00f3rica ciudad, ya se hab\u00edan construido m\u00e1s de 200 palacios, la mayor\u00eda de los cuales a\u00fan perdura.<\/p>\n<p>Hoy Venecia es un im\u00e1n tur\u00edstico, una ciudad que desborda romanticismo. Una imagen extra\u00f1a rodeada de canales y gondoleros, bares y plazas, puentes y vaporettos\u2026Millones de turistas al a\u00f1o, poemas y pel\u00edculas han hecho de Venecia una de las ciudades m\u00e1s famosas del mundo.<\/p>\n<h3><span style=\"color: #008080;\"><strong>Extra\u00f1o destino para la que en otros tiempos fue una de las zonas m\u00e1s desoladas de la Tierra.<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<div>\n<p>&nbsp;<\/p>\n<\/div>\n<form id=\"vozme_form_0ff3982f1088c3700bfe0b0f5c61338a\" method=\"post\" name=\"vozme_form_0ff3982f1088c3700bfe0b0f5c61338a\" target=\"0ff3982f1088c3700bfe0b0f5c61338a\" action=\"http:\/\/vozme.com\/text2voice.php\"><input name=\"text\" type=\"hidden\" value=\"La Venecia del Miedo. La fundaci\u00f3n de las ciudades, siempre est\u00e1 rodeada de hechos heroicos o situaciones forzadas, la mayor\u00eda de las cuales muchas veces se desconoce.\u00a0\nUna de esas historias es la que hoy despierta y evoca im\u00e1genes repletas de pasi\u00f3n.\u00a0 Porque tal vez una de las ciudades m\u00e1s curiosas y rom\u00e1nticas del mundo sea Venecia con sus g\u00f3ndolas que recorren suavemente las aguas del Gran Canal, con sus palacios del Renacimiento reflejados en las tranquilas aguas que todo lo rodean.\u00a0 Venecia es una postal moderna con sus plazas llenas de luz y de amor, junto a las palomas y gaviotas que revolotean pac\u00edficamente por sobre los puentes de arcada.\nSin embargo no hubo nada rom\u00e1ntico en su fundaci\u00f3n. Venecia naci\u00f3 de la desesperaci\u00f3n y el miedo. Hace 1500 a\u00f1os atr\u00e1s, la actual Roma viv\u00eda tiempos complicados. El Imperio romano se estaba cayendo a pedazos y sufr\u00eda la embestida de feroces invasores b\u00e1rbaros del norte, que entraban en su territorio y asolaban lo que se interpusiera en su camino.\nEl \u00e1rea sobre la que actualmente se asienta Venecia, en aquel entonces consist\u00eda en un conjunto de isletas y peque\u00f1os pedazos de tierra sobre una laguna en forma de media luna, totalmente est\u00e9ril, cenagosa, maloliente y mugrienta.\u00a0 No hab\u00eda nada que tuviera a su favor, excepto que era una zona que brindaba, justamente por estas caracter\u00edsticas, cierta seguridad.\nEn el a\u00f1o 452, cuando Atila y sus bravos hunos saquearon la ciudad de Aquilea en tierra firme, los habitantes huyeron a estos pantanos, salvando su pellejo. Un siglo m\u00e1s tarde, la invasi\u00f3n de los lombardos empuj\u00f3 a los aterrorizados pobladores de las ciudades, a buscar refugio en las isletas y as\u00ed fue que, entre desesperaci\u00f3n, miedo y experiencia, los reci\u00e9n llegados aprendieron r\u00e1pidamente a enfrentarse con un medio hostil pero seguro: un entorno acu\u00e1tico de dif\u00edcil subsistencia pero no imposible.\u00a0 Protegieron con estacas las isletas de lodo, construyeron palafitos y unieron las peque\u00f1as zonas sin agua entre s\u00ed rellenando los canales.\nSituada cerca del centro de la laguna, Venecia fue adquiriendo pujanza sobre las dem\u00e1s colonias menores y para el Siglo VIII era una rep\u00fablica aristocr\u00e1tica independiente con un gobernante electo, al que llamaban Dux.\u00a0 As\u00ed siguieron varios siglos de prosperidad econ\u00f3mica, pol\u00edtica y cultural. Nada hac\u00eda prever que pudiera surgir del lodo y la ci\u00e9naga, una pujante e incre\u00edble sociedad. Hacia fines del Siglo XVIII, en el archipi\u00e9lago de bancos de lodo e isletas que componen la hist\u00f3rica ciudad, ya se hab\u00edan construido m\u00e1s de 200 palacios, la mayor\u00eda de los cuales a\u00fan perdura.\nHoy Venecia es un im\u00e1n tur\u00edstico, una ciudad que desborda romanticismo. Una imagen extra\u00f1a rodeada de canales y gondoleros, bares y plazas, puentes y vaporettos\u2026Millones de turistas al a\u00f1o, poemas y pel\u00edculas han hecho de Venecia una de las ciudades m\u00e1s famosas del mundo.\nExtra\u00f1o destino para la que en otros tiempos fue una de las zonas m\u00e1s desoladas de la Tierra.\n&nbsp;\n\n&nbsp;\n\n\" \/><input name=\"lang\" type=\"hidden\" value=\"es\" \/><input name=\"gn\" type=\"hidden\" value=\"ml\" \/><input type=\"hidden\" id=\"interface\" name=\"interface\" value=\"full\" \/>\n\t\t\t<div style=\"text-align:left;\">\n\t\t\t\n\t\t\t\t<input style=\"float:left;\" type=\"image\" width=\"40\" height=\"40\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/plugins\/vozme\/img\/megaphone40x40w.gif\" alt=\"Escucha este post\" onclick=\"window.open('', '0ff3982f1088c3700bfe0b0f5c61338a', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes');\">\n\t\t\t\t<div style=\"margin-left:48px; text-align:left;\"><a style=\"font-size:12px;\" href=\"javascript:void(0);\" onclick=\"window.open('', '0ff3982f1088c3700bfe0b0f5c61338a', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes'); document.getElementById('vozme_form_0ff3982f1088c3700bfe0b0f5c61338a').submit();\">Escucha<br\/>este post<\/a><\/div>\n\t\t\t<\/div><\/form>","protected":false},"excerpt":{"rendered":"<p>La fundaci\u00f3n de las ciudades, siempre est\u00e1 rodeada de hechos heroicos o situaciones forzadas, la mayor\u00eda de las cuales muchas veces se desconoce.\u00a0 Una de esas historias es la que hoy despierta y evoca im\u00e1genes repletas de pasi\u00f3n.\u00a0 Porque tal vez una de las ciudades m\u00e1s curiosas y rom\u00e1nticas del mundo sea Venecia con sus [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5222,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,8,11,1],"tags":[424,212,136],"class_list":["post-5221","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arquitectura","category-ciudades","category-historia","category-sin-categoria","tag-italia","tag-roma","tag-venecia","czr-hentry"],"_links":{"self":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/5221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/comments?post=5221"}],"version-history":[{"count":0,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/5221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media\/5222"}],"wp:attachment":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media?parent=5221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/categories?post=5221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/tags?post=5221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}