{"id":5333,"date":"2017-08-22T00:28:51","date_gmt":"2017-08-22T00:28:51","guid":{"rendered":"http:\/\/ojoscuriosos.com\/?p=5333"},"modified":"2017-08-22T00:28:51","modified_gmt":"2017-08-22T00:28:51","slug":"una-guerra-estupida","status":"publish","type":"post","link":"https:\/\/megatandil.com.ar\/ojoscuriosos\/una-guerra-estupida\/","title":{"rendered":"La Guerra m\u00e1s larga"},"content":{"rendered":"<h2><span style=\"color: #ff0000;\"><strong>Las guerras son siempre sin\u00f3nimos de muerte y destrucci\u00f3n, excepto si la guerra es muy tonta, aunque de estas hay pocas. Una de ellas es la guerra entre Holanda y las islas Scilly.<\/strong><\/span><\/h2>\n<p>En abril de 1986 los holandeses le pusieron fin a la guerra m\u00e1s prolongada en la historia de esa naci\u00f3n y quiz\u00e1s del mundo. Su embajador en Londres vol\u00f3 a St. Mary, en las islas Scilly frente a la costa sudoeste de Inglaterra, con una declaraci\u00f3n de paz que termin\u00f3 con un conflicto que hab\u00eda durado 335 a\u00f1os, entre Holanda y ese pl\u00e1cido archipi\u00e9lago.<\/p>\n<figure id=\"attachment_5334\" aria-describedby=\"caption-attachment-5334\" style=\"width: 990px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/a_14655076-a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-5334\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/a_14655076-a.jpg\" alt=\"Islas Scilly\" width=\"990\" height=\"640\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/a_14655076-a.jpg 990w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/a_14655076-a-300x194.jpg 300w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/a_14655076-a-768x496.jpg 768w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/a><figcaption id=\"caption-attachment-5334\" class=\"wp-caption-text\">Islas Scilly<\/figcaption><\/figure>\n<p>Durante todo ese tiempo no se lanz\u00f3 un solo tiro ni se derram\u00f3 una sola gota de sangre. Comenz\u00f3 como un extra\u00f1o resultado de la primera revoluci\u00f3n inglesa. En un intento de llenar sus arcas vac\u00edas, los monarcas otorgaron a los isle\u00f1os de Scilly, que hab\u00edan apoyado al rey contra el Parlamento, el derecho de practicar \u201cexpediciones leg\u00edtimas\u201d. O sea, dicho claramente, a efectuar actos de pirater\u00eda.<\/p>\n<p>Eso afect\u00f3 fundamentalmete a los holandeses, porque sus barcos pasaban cerca de las islas, camino a las Indias orientales. En 1651, el almirante holand\u00e9s Maarten Tromp orden\u00f3 a los isle\u00f1os que desistieran de ser piratas, pero estos se negaron y all\u00ed nom\u00e1s se les declar\u00f3 la guerra.<\/p>\n<p>Poco despu\u00e9s fue Tromp, quien recibi\u00f3 de la marina brit\u00e1nica, la orden de no interferir, ya que los ingleses podr\u00edan resolver sus propios problemas. Y as\u00ed, sin m\u00e1s ni m\u00e1s, la historia pareci\u00f3 concluir, pero no oficialmente.<\/p>\n<p>Hasta 1985, nadie se hab\u00eda percatado que la guerra nunca hab\u00eda terminado en los papeles. No hab\u00eda un solo sello ni firma que rubricara el fin de las disputas, o sea que la guerra estaba en pie.\u00a0 Esta est\u00fapida contienda donde nadie pele\u00f3 y donde ni siquiera un ca\u00f1onazo perturb\u00f3 la tranquilidad de las islas, dur\u00f3 m\u00e1s de tres siglos y\u00a0 finaliz\u00f3 gracias a que alguien, en Holanda, decidi\u00f3 revisar la historia.<\/p>\n<p>Dicen los ir\u00f3nicos que la lucha termin\u00f3 porque los isle\u00f1os esperaban atraer turistas de Holanda, ya que desde hac\u00eda mucho tiempo hab\u00edan dejado de aparecer los barcos de guerra holandeses o las embarcaciones para piratear.<\/p>\n<h4><strong>La historia del mundo est\u00e1 plagada de hechos est\u00fapidos.<\/strong><\/h4>\n<p>&nbsp;<\/p>\n<form id=\"vozme_form_ea583378bfbcbc135df8c1ea8b42eb7a\" method=\"post\" name=\"vozme_form_ea583378bfbcbc135df8c1ea8b42eb7a\" target=\"ea583378bfbcbc135df8c1ea8b42eb7a\" action=\"http:\/\/vozme.com\/text2voice.php\"><input name=\"text\" type=\"hidden\" value=\"La Guerra m\u00e1s larga. Las guerras son siempre sin\u00f3nimos de muerte y destrucci\u00f3n, excepto si la guerra es muy tonta, aunque de estas hay pocas. Una de ellas es la guerra entre Holanda y las islas Scilly.\nEn abril de 1986 los holandeses le pusieron fin a la guerra m\u00e1s prolongada en la historia de esa naci\u00f3n y quiz\u00e1s del mundo. Su embajador en Londres vol\u00f3 a St. Mary, en las islas Scilly frente a la costa sudoeste de Inglaterra, con una declaraci\u00f3n de paz que termin\u00f3 con un conflicto que hab\u00eda durado 335 a\u00f1os, entre Holanda y ese pl\u00e1cido archipi\u00e9lago.\n[caption id=&quot;attachment_5334&quot; align=&quot;alignleft&quot; width=&quot;990&quot;] Islas Scilly[\/caption]\nDurante todo ese tiempo no se lanz\u00f3 un solo tiro ni se derram\u00f3 una sola gota de sangre. Comenz\u00f3 como un extra\u00f1o resultado de la primera revoluci\u00f3n inglesa. En un intento de llenar sus arcas vac\u00edas, los monarcas otorgaron a los isle\u00f1os de Scilly, que hab\u00edan apoyado al rey contra el Parlamento, el derecho de practicar \u201cexpediciones leg\u00edtimas\u201d. O sea, dicho claramente, a efectuar actos de pirater\u00eda.\nEso afect\u00f3 fundamentalmete a los holandeses, porque sus barcos pasaban cerca de las islas, camino a las Indias orientales. En 1651, el almirante holand\u00e9s Maarten Tromp orden\u00f3 a los isle\u00f1os que desistieran de ser piratas, pero estos se negaron y all\u00ed nom\u00e1s se les declar\u00f3 la guerra.\nPoco despu\u00e9s fue Tromp, quien recibi\u00f3 de la marina brit\u00e1nica, la orden de no interferir, ya que los ingleses podr\u00edan resolver sus propios problemas. Y as\u00ed, sin m\u00e1s ni m\u00e1s, la historia pareci\u00f3 concluir, pero no oficialmente.\nHasta 1985, nadie se hab\u00eda percatado que la guerra nunca hab\u00eda terminado en los papeles. No hab\u00eda un solo sello ni firma que rubricara el fin de las disputas, o sea que la guerra estaba en pie.\u00a0 Esta est\u00fapida contienda donde nadie pele\u00f3 y donde ni siquiera un ca\u00f1onazo perturb\u00f3 la tranquilidad de las islas, dur\u00f3 m\u00e1s de tres siglos y\u00a0 finaliz\u00f3 gracias a que alguien, en Holanda, decidi\u00f3 revisar la historia.\nDicen los ir\u00f3nicos que la lucha termin\u00f3 porque los isle\u00f1os esperaban atraer turistas de Holanda, ya que desde hac\u00eda mucho tiempo hab\u00edan dejado de aparecer los barcos de guerra holandeses o las embarcaciones para piratear.\nLa historia del mundo est\u00e1 plagada de hechos est\u00fapidos.\n&nbsp;\n\" \/><input name=\"lang\" type=\"hidden\" value=\"es\" \/><input name=\"gn\" type=\"hidden\" value=\"ml\" \/><input type=\"hidden\" id=\"interface\" name=\"interface\" value=\"full\" \/>\n\t\t\t<div style=\"text-align:left;\">\n\t\t\t\n\t\t\t\t<input style=\"float:left;\" type=\"image\" width=\"40\" height=\"40\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/plugins\/vozme\/img\/megaphone40x40w.gif\" alt=\"Escucha este post\" onclick=\"window.open('', 'ea583378bfbcbc135df8c1ea8b42eb7a', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes');\">\n\t\t\t\t<div style=\"margin-left:48px; text-align:left;\"><a style=\"font-size:12px;\" href=\"javascript:void(0);\" onclick=\"window.open('', 'ea583378bfbcbc135df8c1ea8b42eb7a', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes'); document.getElementById('vozme_form_ea583378bfbcbc135df8c1ea8b42eb7a').submit();\">Escucha<br\/>este post<\/a><\/div>\n\t\t\t<\/div><\/form>","protected":false},"excerpt":{"rendered":"<p>Las guerras son siempre sin\u00f3nimos de muerte y destrucci\u00f3n, excepto si la guerra es muy tonta, aunque de estas hay pocas. Una de ellas es la guerra entre Holanda y las islas Scilly. En abril de 1986 los holandeses le pusieron fin a la guerra m\u00e1s prolongada en la historia de esa naci\u00f3n y quiz\u00e1s [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,1],"tags":[539,115],"class_list":["post-5333","post","type-post","status-publish","format-standard","has-post-thumbnail","category-historia","category-sin-categoria","tag-estupidez","tag-guerra","czr-hentry"],"_links":{"self":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/5333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/comments?post=5333"}],"version-history":[{"count":0,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/5333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media\/5334"}],"wp:attachment":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media?parent=5333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/categories?post=5333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/tags?post=5333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}