{"id":5360,"date":"2017-08-30T02:27:46","date_gmt":"2017-08-30T02:27:46","guid":{"rendered":"http:\/\/ojoscuriosos.com\/?p=5360"},"modified":"2017-08-30T02:27:46","modified_gmt":"2017-08-30T02:27:46","slug":"los-rayos-de-sullivan","status":"publish","type":"post","link":"https:\/\/megatandil.com.ar\/ojoscuriosos\/los-rayos-de-sullivan\/","title":{"rendered":"Los Rayos de Sullivan"},"content":{"rendered":"<h2><span style=\"color: #008080;\">Hay gente que, bas\u00e1ndonos en el mismo hecho, no se sabe si son personas afortunadas o no. \u00bfQu\u00e9 puede decirse de un hombre que ha recibido <span style=\"color: #008000;\">siete ca\u00eddas de rayo sobre \u00e9l<\/span>?. \u00bf Es mala suerte sufrir tantas veces lo mismo o es buena suerte salvarse?<a href=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/descarga-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-5361\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/descarga-1.jpg\" alt=\"descarga (1)\" width=\"208\" height=\"228\" \/><\/a><a href=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/rayo004_1600x1200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5363\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/rayo004_1600x1200-300x225.jpg\" alt=\"rayo004_1600x1200\" width=\"300\" height=\"225\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/rayo004_1600x1200-300x225.jpg 300w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/rayo004_1600x1200-768x576.jpg 768w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/rayo004_1600x1200-1024x768.jpg 1024w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2014\/05\/rayo004_1600x1200.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/span><\/h2>\n<p>El guardabosques estadounidense <strong>Roy Sullivan<\/strong> es el hombre a quien le han ca\u00eddo mas rayos. El primero lo sorprendi\u00f3 en 1942 y en 1977 fue la s\u00e9ptima vez. En cada ocasi\u00f3n result\u00f3 lesionado: primero perdi\u00f3 una u\u00f1a de un pie, luego se le quemaron las cejas, se le chamusc\u00f3 un hombro, se le incendi\u00f3 el pelo y sufri\u00f3 quemaduras en las piernas\u2026pero sobrevivi\u00f3.<\/p>\n<p>Un rayo puede caer a tierra a una velocidad de hasta 1600 kmts por segundo y generar una temperatura de hasta 30.000\u00a0 grados Centigrados, seis veces m\u00e1s altas que la de la superficie del sol. Por eso resulta asombroso que mucha gente azotada por tan violento fen\u00f3meno, pueda sobrevivir para contarlo.<\/p>\n<p>El rayo es una chispa el\u00e9ctrica causada por la diferencia de energ\u00eda que existe entre las nubes y el aire circundante o el suelo. Dicha energ\u00eda busca la ruta mas corta para llegar a tierra y puede atravesar cuanto objeto encuentre a su paso.<\/p>\n<p>En una persona, la ruta mas corta puede ser por el hombro y luego por el costado del cuerpo hasta la pierna, para finalmente entrar en tierra. El rayo puede causar dolor, conmoci\u00f3n o quemaduras, pero la mayor parte se descarga en el suelo. Mientras no atraviese el coraz\u00f3n o la m\u00e9dula espinal, es probable que la v\u00edctima no muera, de lo contrario la muerte es fulminante.<\/p>\n<p><strong>Lo cierto del caso es que Sullivan sorte\u00f3 todo eso siete veces y vivi\u00f3 para contarlo. Sencillamente incre\u00edble.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<form id=\"vozme_form_a070cae98ad16f4bc0f6c8bb716b814e\" method=\"post\" name=\"vozme_form_a070cae98ad16f4bc0f6c8bb716b814e\" target=\"a070cae98ad16f4bc0f6c8bb716b814e\" action=\"http:\/\/vozme.com\/text2voice.php\"><input name=\"text\" type=\"hidden\" value=\"Los Rayos de Sullivan. Hay gente que, bas\u00e1ndonos en el mismo hecho, no se sabe si son personas afortunadas o no. \u00bfQu\u00e9 puede decirse de un hombre que ha recibido siete ca\u00eddas de rayo sobre \u00e9l?. \u00bf Es mala suerte sufrir tantas veces lo mismo o es buena suerte salvarse?\nEl guardabosques estadounidense Roy Sullivan es el hombre a quien le han ca\u00eddo mas rayos. El primero lo sorprendi\u00f3 en 1942 y en 1977 fue la s\u00e9ptima vez. En cada ocasi\u00f3n result\u00f3 lesionado: primero perdi\u00f3 una u\u00f1a de un pie, luego se le quemaron las cejas, se le chamusc\u00f3 un hombro, se le incendi\u00f3 el pelo y sufri\u00f3 quemaduras en las piernas\u2026pero sobrevivi\u00f3.\nUn rayo puede caer a tierra a una velocidad de hasta 1600 kmts por segundo y generar una temperatura de hasta 30.000\u00a0 grados Centigrados, seis veces m\u00e1s altas que la de la superficie del sol. Por eso resulta asombroso que mucha gente azotada por tan violento fen\u00f3meno, pueda sobrevivir para contarlo.\nEl rayo es una chispa el\u00e9ctrica causada por la diferencia de energ\u00eda que existe entre las nubes y el aire circundante o el suelo. Dicha energ\u00eda busca la ruta mas corta para llegar a tierra y puede atravesar cuanto objeto encuentre a su paso.\nEn una persona, la ruta mas corta puede ser por el hombro y luego por el costado del cuerpo hasta la pierna, para finalmente entrar en tierra. El rayo puede causar dolor, conmoci\u00f3n o quemaduras, pero la mayor parte se descarga en el suelo. Mientras no atraviese el coraz\u00f3n o la m\u00e9dula espinal, es probable que la v\u00edctima no muera, de lo contrario la muerte es fulminante.\nLo cierto del caso es que Sullivan sorte\u00f3 todo eso siete veces y vivi\u00f3 para contarlo. Sencillamente incre\u00edble.\n&nbsp;\n\" \/><input name=\"lang\" type=\"hidden\" value=\"es\" \/><input name=\"gn\" type=\"hidden\" value=\"ml\" \/><input type=\"hidden\" id=\"interface\" name=\"interface\" value=\"full\" \/>\n\t\t\t<div style=\"text-align:left;\">\n\t\t\t\n\t\t\t\t<input style=\"float:left;\" type=\"image\" width=\"40\" height=\"40\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/plugins\/vozme\/img\/megaphone40x40w.gif\" alt=\"Escucha este post\" onclick=\"window.open('', 'a070cae98ad16f4bc0f6c8bb716b814e', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes');\">\n\t\t\t\t<div style=\"margin-left:48px; text-align:left;\"><a style=\"font-size:12px;\" href=\"javascript:void(0);\" onclick=\"window.open('', 'a070cae98ad16f4bc0f6c8bb716b814e', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes'); document.getElementById('vozme_form_a070cae98ad16f4bc0f6c8bb716b814e').submit();\">Escucha<br\/>este post<\/a><\/div>\n\t\t\t<\/div><\/form>","protected":false},"excerpt":{"rendered":"<p>Hay gente que, bas\u00e1ndonos en el mismo hecho, no se sabe si son personas afortunadas o no. \u00bfQu\u00e9 puede decirse de un hombre que ha recibido siete ca\u00eddas de rayo sobre \u00e9l?. \u00bf Es mala suerte sufrir tantas veces lo mismo o es buena suerte salvarse? El guardabosques estadounidense Roy Sullivan es el hombre a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71,34,16,13,5,1],"tags":[318,546],"class_list":["post-5360","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cuerpo-humano","category-fenomenos","category-naturaleza","category-personajes","category-rarezas-2","category-sin-categoria","tag-milagro","tag-rayo","czr-hentry"],"_links":{"self":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/5360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/comments?post=5360"}],"version-history":[{"count":0,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/5360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media\/5362"}],"wp:attachment":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media?parent=5360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/categories?post=5360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/tags?post=5360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}