{"id":634,"date":"2018-02-03T00:01:22","date_gmt":"2018-02-03T00:01:22","guid":{"rendered":"http:\/\/ojoscuriosos.com\/?p=634"},"modified":"2018-02-03T00:01:22","modified_gmt":"2018-02-03T00:01:22","slug":"el-partido-de-la-muerte","status":"publish","type":"post","link":"https:\/\/megatandil.com.ar\/ojoscuriosos\/el-partido-de-la-muerte\/","title":{"rendered":"Nazis y F\u00fatbol"},"content":{"rendered":"<h2><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/images-130.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2146\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/images-130.jpg\" alt=\"images (1)\" width=\"276\" height=\"182\" \/><\/a><span style=\"color: #ff0000;\">Durante el transcurso de la Segunda Guerra Mundial, <strong>Kiev, la capital de Ucrania<\/strong> fue tomada por los nazis. Una de las cosas que prohibieron los alemanes fue el f\u00fatbol ya que el equipo estrella de la capital, el <strong>Dynamo<\/strong> de Kiev, hab\u00eda sido fundado por miembros de la polic\u00eda comunista. Sin embargo, y de manera clandestina, muchos jugadores segu\u00edan practicando el deporte luego de cambiar el nombre del equipo por el de <strong>Star,<\/strong> para no despertar sospechas.<\/span><\/h2>\n<p>A pesar de una alimentaci\u00f3n deficiente los ucranianos segu\u00edan jugando bien y ganando partidos hasta hacerse muy populares pese a la prohibici\u00f3n. Un d\u00eda se enfrentaron a un equipo alem\u00e1n y les ganaron, lo cual enoj\u00f3 mucho a los jerarcas nazis, que optaron por presentar un mejor conjunto al cual tambi\u00e9n derrotaron. Eso hizo que los jugadores del Star pasaran a ser muy famosos ante la ira de los militares alemanes que no pod\u00edan detener esa popularidad. Algunos nazis propusieron fusilar a todos los futbolistas, pero muchos sab\u00edan que eso elevar\u00eda a los deportistas a la categor\u00eda de m\u00e1rtires y aumentar\u00eda la leyenda, as\u00ed que decidieron organizar un encuentro oficial con los mejores jugadores de las <strong>Werhmacht<\/strong>, las fuerzas nazis.<\/p>\n<p>El equipo alem\u00e1n se llamaba <strong>Flakelf<\/strong> y fueron derrotados en el primer partido. Pidieron la revancha obligatoria y se prepararon fieramente sabiendo que se jugaban todo el prestigio de la fuerza. El partido final se jug\u00f3 en el estadio Zenith el 6 de agosto de 1942, con los palcos cubiertos de autoridades y jerarcas nazis. El resultado, de ser negativo, desafiar\u00eda a todo el r\u00e9gimen de Hitler y ser\u00eda conocido a partir de ese momento, como el <em><strong>\u201cpartido de la muerte\u201d<\/strong><\/em>. Un \u00e1rbitro alem\u00e1n por supuesto, le pide al equipo de los Star que al salir haga el saludo nazi, cosa que el equipo no respeta y provoca mayor ira en los militares.<\/p>\n<p>El primer tiempo, lleno de infracciones y patadas alemanas, termina 2 a 1 a favor de Ucrania. Un alto jefe nazi, el comandante de la ocupaci\u00f3n, un tal <strong>Eberhardt<\/strong>, pistola en mano baja al vestuario y amenaza a los Star dici\u00e9ndoles que si ganan habr\u00e1 consecuencias porque nunca un equipo alem\u00e1n perdi\u00f3 en territorios ocupados. Pese a eso el partido termina 5 a 3 a favor de Ucrania. Fue el principio del fin.<\/p>\n<p>Varios jugadores fueron secuestrados y torturados por la<strong> Gestapo,<\/strong> mientras que otros fueron enviados al campo de concentraci\u00f3n <strong>Syrets<\/strong> donde fueron asesinados. <strong>Mykola Trusevich<\/strong>, el arquero de aquel glorioso equipo de Kiev, pidi\u00f3 ser muerto con la camiseta puesta en una ma\u00f1ana de febrero de 1943. Actualmente hay un monumento que recuerda el hecho frente al estadio Zenith, los jugadores son considerados h\u00e9roes y su historia se ense\u00f1a en los colegios.<\/p>\n<p><strong>Como homenaje p\u00f3stu<\/strong><strong>mo, todos los que conserven una entrada de aquel d\u00eda, sean hijos o nietos de los espectadores, tienen un pase de por vida para ver todos los partidos del Dynamo de Kiev.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_638\" aria-describedby=\"caption-attachment-638\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/odioeternoalfutbolmoderno-el_partido_de_la_muerte_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-638\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/odioeternoalfutbolmoderno-el_partido_de_la_muerte_-300x198.jpg\" alt=\"Los dos equipos antes del partido. Los de camiseta oscura son los ucranianos.\" width=\"300\" height=\"198\" \/><\/a><figcaption id=\"caption-attachment-638\" class=\"wp-caption-text\">Los dos equipos antes del partido. Los de camiseta oscura son los ucranianos.<\/figcaption><\/figure>\n<p><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/Dinamo-de-Kiev-vs.-Nazis.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-636\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/Dinamo-de-Kiev-vs.-Nazis-300x218.jpeg\" alt=\"Dinamo de Kiev vs. Nazis\" width=\"300\" height=\"218\" \/><\/a><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/u4fc-start-memorial.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-639\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2013\/07\/u4fc-start-memorial-269x300.jpg\" alt=\"u4fc-start-memorial\" width=\"269\" height=\"300\" \/><\/a><\/p>\n<form id=\"vozme_form_c65835091c1992bae3771f721c770b9c\" method=\"post\" name=\"vozme_form_c65835091c1992bae3771f721c770b9c\" target=\"c65835091c1992bae3771f721c770b9c\" action=\"http:\/\/vozme.com\/text2voice.php\"><input name=\"text\" type=\"hidden\" value=\"Nazis y F\u00fatbol. Durante el transcurso de la Segunda Guerra Mundial, Kiev, la capital de Ucrania fue tomada por los nazis. Una de las cosas que prohibieron los alemanes fue el f\u00fatbol ya que el equipo estrella de la capital, el Dynamo de Kiev, hab\u00eda sido fundado por miembros de la polic\u00eda comunista. Sin embargo, y de manera clandestina, muchos jugadores segu\u00edan practicando el deporte luego de cambiar el nombre del equipo por el de Star, para no despertar sospechas.\nA pesar de una alimentaci\u00f3n deficiente los ucranianos segu\u00edan jugando bien y ganando partidos hasta hacerse muy populares pese a la prohibici\u00f3n. Un d\u00eda se enfrentaron a un equipo alem\u00e1n y les ganaron, lo cual enoj\u00f3 mucho a los jerarcas nazis, que optaron por presentar un mejor conjunto al cual tambi\u00e9n derrotaron. Eso hizo que los jugadores del Star pasaran a ser muy famosos ante la ira de los militares alemanes que no pod\u00edan detener esa popularidad. Algunos nazis propusieron fusilar a todos los futbolistas, pero muchos sab\u00edan que eso elevar\u00eda a los deportistas a la categor\u00eda de m\u00e1rtires y aumentar\u00eda la leyenda, as\u00ed que decidieron organizar un encuentro oficial con los mejores jugadores de las Werhmacht, las fuerzas nazis.\nEl equipo alem\u00e1n se llamaba Flakelf y fueron derrotados en el primer partido. Pidieron la revancha obligatoria y se prepararon fieramente sabiendo que se jugaban todo el prestigio de la fuerza. El partido final se jug\u00f3 en el estadio Zenith el 6 de agosto de 1942, con los palcos cubiertos de autoridades y jerarcas nazis. El resultado, de ser negativo, desafiar\u00eda a todo el r\u00e9gimen de Hitler y ser\u00eda conocido a partir de ese momento, como el \u201cpartido de la muerte\u201d. Un \u00e1rbitro alem\u00e1n por supuesto, le pide al equipo de los Star que al salir haga el saludo nazi, cosa que el equipo no respeta y provoca mayor ira en los militares.\nEl primer tiempo, lleno de infracciones y patadas alemanas, termina 2 a 1 a favor de Ucrania. Un alto jefe nazi, el comandante de la ocupaci\u00f3n, un tal Eberhardt, pistola en mano baja al vestuario y amenaza a los Star dici\u00e9ndoles que si ganan habr\u00e1 consecuencias porque nunca un equipo alem\u00e1n perdi\u00f3 en territorios ocupados. Pese a eso el partido termina 5 a 3 a favor de Ucrania. Fue el principio del fin.\nVarios jugadores fueron secuestrados y torturados por la Gestapo, mientras que otros fueron enviados al campo de concentraci\u00f3n Syrets donde fueron asesinados. Mykola Trusevich, el arquero de aquel glorioso equipo de Kiev, pidi\u00f3 ser muerto con la camiseta puesta en una ma\u00f1ana de febrero de 1943. Actualmente hay un monumento que recuerda el hecho frente al estadio Zenith, los jugadores son considerados h\u00e9roes y su historia se ense\u00f1a en los colegios.\nComo homenaje p\u00f3stumo, todos los que conserven una entrada de aquel d\u00eda, sean hijos o nietos de los espectadores, tienen un pase de por vida para ver todos los partidos del Dynamo de Kiev.\n&nbsp;\n[caption id=&quot;attachment_638&quot; align=&quot;alignleft&quot; width=&quot;300&quot;] Los dos equipos antes del partido. Los de camiseta oscura son los ucranianos.[\/caption]\n\n\" \/><input name=\"lang\" type=\"hidden\" value=\"es\" \/><input name=\"gn\" type=\"hidden\" value=\"ml\" \/><input type=\"hidden\" id=\"interface\" name=\"interface\" value=\"full\" \/>\n\t\t\t<div style=\"text-align:left;\">\n\t\t\t\n\t\t\t\t<input style=\"float:left;\" type=\"image\" width=\"40\" height=\"40\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/plugins\/vozme\/img\/megaphone40x40w.gif\" alt=\"Escucha este post\" onclick=\"window.open('', 'c65835091c1992bae3771f721c770b9c', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes');\">\n\t\t\t\t<div style=\"margin-left:48px; text-align:left;\"><a style=\"font-size:12px;\" href=\"javascript:void(0);\" onclick=\"window.open('', 'c65835091c1992bae3771f721c770b9c', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes'); document.getElementById('vozme_form_c65835091c1992bae3771f721c770b9c').submit();\">Escucha<br\/>este post<\/a><\/div>\n\t\t\t<\/div><\/form>","protected":false},"excerpt":{"rendered":"<p>Durante el transcurso de la Segunda Guerra Mundial, Kiev, la capital de Ucrania fue tomada por los nazis. Una de las cosas que prohibieron los alemanes fue el f\u00fatbol ya que el equipo estrella de la capital, el Dynamo de Kiev, hab\u00eda sido fundado por miembros de la polic\u00eda comunista. Sin embargo, y de manera [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[214,11,1],"tags":[215,261,575,785],"class_list":["post-634","post","type-post","status-publish","format-standard","has-post-thumbnail","category-deporte","category-historia","category-sin-categoria","tag-futbol","tag-muerte","tag-nazis","tag-partido","czr-hentry"],"_links":{"self":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/comments?post=634"}],"version-history":[{"count":0,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media\/640"}],"wp:attachment":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media?parent=634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/categories?post=634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/tags?post=634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}