{"id":6947,"date":"2016-11-23T01:54:18","date_gmt":"2016-11-23T01:54:18","guid":{"rendered":"http:\/\/ojoscuriosos.com\/?p=6947"},"modified":"2016-11-23T01:54:18","modified_gmt":"2016-11-23T01:54:18","slug":"la-isla-colares","status":"publish","type":"post","link":"https:\/\/megatandil.com.ar\/ojoscuriosos\/la-isla-colares\/","title":{"rendered":"La Isla Colares"},"content":{"rendered":"<h2><span style=\"color: #333399;\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6958\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/ovnisJHG.jpg\" alt=\"ovnisJHG\" width=\"1300\" height=\"600\" \/>En el estado brasile\u00f1o de Par\u00e1, a la altura de la desembocadura del Amazonas, se encuentra la isla Colares.\u00a0 En este lugar, hasta entonces casi an\u00f3nimo, se produjeron en el a\u00f1o 1977 una serie de sucesos que a\u00fan no tienen explicaci\u00f3n.<\/span><\/h2>\n<p>Sus habitantes comenzaron a reportar una abundante cantidad de avistamientos de ovnis de todo tipo, luces esf\u00e9ricas, conos luminosos, platillos y cilindros atemorizantes.\u00a0 No hubiera sido diferente de otros casos mundiales, si no fuera porque los aterrorizados pobladores relataban que estas naves luminosas se aparec\u00edan sorpresivamente y les lanzaban una especie de rayo de luz que, de acuerdo a los testigos, les succionaba la sangre o al menos daba esa sensaci\u00f3n.\u00a0 As\u00ed fue que a este desagradable fen\u00f3meno se lo empez\u00f3 a llamar \u201cchupa-chupa\u201d.<a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/aso-colares-periodico-6.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-6953\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/aso-colares-periodico-6.png\" alt=\"aso-colares-periodico-6\" width=\"500\" height=\"392\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2015\/03\/aso-colares-periodico-6.png 500w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2015\/03\/aso-colares-periodico-6-300x235.png 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>El caso pas\u00f3 a mayores, puesto que las luces continuaron fastidiando durante muchos meses a la gente, sigui\u00e9ndolos incluso hasta dentro de sus propias viviendas lleg\u00e1ndose a conocer reportes de luces que los \u201cvisitaban\u201d por las madrugadas,\u00a0atravesando\u00a0sus techos e iluminando partes de sus cuerpos, causando ardor o quemaduras en las zonas que ten\u00edan contacto con esas luces. Se las vio tambi\u00e9n en la iglesia del pueblo, que era el lugar donde la mayor\u00eda hu\u00eda creyendo que iban a encontrar un poco de paz.\u00a0\u00a0 Muchas de las v\u00edctimas relataron que al entrar en contacto con su piel desnuda pod\u00edan\u00a0sentir como sus cuerpos se paralizaban y empezaban a sentir quemaduras en las zonas iluminadas.<\/p>\n<p>Una de las personas que le toc\u00f3 vivir la tragedia fue la joven m\u00e9dica brasile\u00f1a <em><strong>Wellaide Cecim Carvalho<\/strong><\/em>, quien se dedic\u00f3 a atender a los numerosos pacientes que llegaban con quemaduras en su cuello o pecho.<\/p>\n<p>La Dra. Wellaide recuerda haber atendido a unos 35 o 40 pacientes aunque los damnificados fueron m\u00e1s de 80 a lo largo de casi un a\u00f1o, incluso con dos muertos adjudicados al fen\u00f3meno. \u00a0De acuerdo a la m\u00e9dica, los pacientes presentaban sensaci\u00f3n de debilidad al punto que les resultaba dif\u00edcil caminar. Los testigos adem\u00e1s ten\u00edan quemaduras con necrosis tan solo minutos despu\u00e9s de haber sufrido un ataque por un OVNI, siendo que la necrosis en quemaduras normales se produce unas 90 horas despu\u00e9s de efectuada la acci\u00f3n.<\/p>\n<figure id=\"attachment_6954\" aria-describedby=\"caption-attachment-6954\" style=\"width: 175px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/colares_carvalho.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6954\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/colares_carvalho.jpg\" alt=\"Doctora Carvalho\" width=\"175\" height=\"263\" \/><\/a><figcaption id=\"caption-attachment-6954\" class=\"wp-caption-text\">Doctora Carvalho<\/figcaption><\/figure>\n<p>Las v\u00edctimas presentaban adem\u00e1s, unas peque\u00f1as incisiones, con la sensaci\u00f3n de picaduras de viruela o peque\u00f1os agujeritos tipo inyecci\u00f3n, en los sectores quemados. Asimismo, los hemogramas de los pacientes mostraban que \u00e9stos ten\u00edan una fuerte disminuci\u00f3n de los eritrocitos y hemoglobina, es decir, anemia. Wellaide tambi\u00e9n relat\u00f3 un avistamiento que tuvo ella, de un objeto met\u00e1lico en forma de cono truncado que se pase\u00f3 por el centro del pueblo a muy baja altura un d\u00eda a mediatarde, luego de atacar a una se\u00f1ora que qued\u00f3 desvanecida. . Recuerda adem\u00e1s, que dentro del aparato volador, pod\u00edan verse dos seres\u00a0peque\u00f1os, de poco m\u00e1s de un metro de altura.<\/p>\n<p>De acuerdo a la doctora Wellaide, dos de los pacientes que ella atendi\u00f3 murieron por causa de estos ataques, aunque se declar\u00f3 que el deceso fue por causas desconocidas.<\/p>\n<p>Lo que ocurri\u00f3 despu\u00e9s fue que la Fuerza A\u00e9rea, presionada ante la dram\u00e1tica situaci\u00f3n que se estaba viviendo en Colares, se vio obligada a actuar. De esa manera se inici\u00f3 la \u201cOperaci\u00f3n Prato\u201d (platillo en portugu\u00e9s). Un grupo de militares se dedico a investigar que estaba sucediendo en Colares y sus alrededores. Sin embargo, llegaron 90 d\u00edas despu\u00e9s del cl\u00edmax de la tragedia, cuando Colares ya estaba siendo \u00a0abandonado por casi todos sus asustados habitantes.<\/p>\n<figure id=\"attachment_6951\" aria-describedby=\"caption-attachment-6951\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/aso-colares-evidencias-7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6951\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/aso-colares-evidencias-7.jpg\" alt=\"Dibujos de los testigos\" width=\"300\" height=\"223\" \/><\/a><figcaption id=\"caption-attachment-6951\" class=\"wp-caption-text\">Dibujos de los testigos<\/figcaption><\/figure>\n<p><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/aso-colares-evidencias-8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-6952\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/aso-colares-evidencias-8.jpg\" alt=\"aso-colares-evidencias-8\" width=\"520\" height=\"411\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2015\/03\/aso-colares-evidencias-8.jpg 520w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2015\/03\/aso-colares-evidencias-8-300x237.jpg 300w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/a><\/p>\n<p>Desde el punto de vista oficial, en mayo del 2004, o sea 27 a\u00f1os mas tarde, se realiz\u00f3 una reuni\u00f3n entre varios generales de alto rango de la Fuerza A\u00e9rea Brasile\u00f1a con varios uf\u00f3logos brasile\u00f1os. Los militares hicieron entrega de algunos archivos recopilados durante el transcurso de la \u201cOperaci\u00f3n Prato\u201d, para disposici\u00f3n y an\u00e1lisis de los uf\u00f3logos. Conforme con los documentos liberados, en 1977 los militares hab\u00edan tomado fotos de los OVNIs, entrevistaron a muchos testigos y tuvieron encuentros cercanos, logrando hacer dibujos de los objetos y de sus trayectorias.<\/p>\n<p>El comandante del grupo de estudio era un militar, que era inicialmente esc\u00e9ptico, y pretend\u00eda desmitificar el asunto y explicarlo de manera l\u00f3gica como psicosis colectiva.\u00a0 Sin embargo, su opini\u00f3n fue cambiando hasta darse cuenta que algo grave hab\u00eda ocurrido en el lugar. Se trataba del Coronel<strong> Uyrange Hollanda Lima<\/strong>. De acuerdo a una entrevista realizada a Hollanda, los lugare\u00f1os frecuentemente les disparaban a los OVNIs. En palabras de Hollanda<em>:<strong> \u201cSiempre les dec\u00edamos: no les disparen, no les disparen. Una vez, una fuerte luz hab\u00eda sido apuntada a un carpintero. El hombre ten\u00eda unos 50 o 60 a\u00f1os. Tom\u00f3 su rifle y le dispar\u00f3 al platillo volador. La luz lo rode\u00f3, y \u00e9l cay\u00f3 al suelo, casi paralizado. Durante 15 d\u00edas el carpintero apenas se pudo mover. Pod\u00eda hablar y escuchar pero le resultaba dif\u00edcil moverse\u201d<\/strong>.<\/em><\/p>\n<p>Los \u00faltimos relatos del coronel consistieron en decir que \u00e9l, junto con un compa\u00f1ero, hab\u00eda tenido tambi\u00e9n un fugaz contacto con uno de los tripulantes de los OVNIs. Seg\u00fan relat\u00f3, el tripulante baj\u00f3 de su nave y se puso delante de los dos militares, los mir\u00f3 en silencio a los ojos, y luego retorn\u00f3 a su nave a\u00e9rea. Hollanda menciona que cuando hizo el reporte militar acerca de este contacto con el ser humanoide, la Fuerza A\u00e9rea Brasile\u00f1a, dio por terminada inmediatamente la Operaci\u00f3n Prato, y guard\u00f3 los archivos de la operaci\u00f3n iniciando un prolongado silencio oficial. Las declaraciones de Hollanda le ocasionaron un enorme descr\u00e9dito y una dura campa\u00f1a en su contra.<\/p>\n<figure id=\"attachment_6956\" aria-describedby=\"caption-attachment-6956\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/dnot_5062.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6956\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/dnot_5062-300x221.jpg\" alt=\"Vecina luego de un ataque\" width=\"300\" height=\"221\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2015\/03\/dnot_5062-300x221.jpg 300w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2015\/03\/dnot_5062.jpg 380w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-6956\" class=\"wp-caption-text\">Vecina luego de un ataque<\/figcaption><\/figure>\n<p><a href=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/colares-case_byark.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-6955\" src=\"http:\/\/ojoscuriosos.com\/wp-content\/uploads\/2015\/03\/colares-case_byark.gif\" alt=\"colares-case_byark\" width=\"500\" height=\"380\" \/><\/a><\/p>\n<p>De hecho, la misma Dra. Wellaide relata haber recibido presiones por parte de los militares:<strong> <em>\u201cFui obligada por la Fuerza A\u00e9rea Brasile\u00f1a a convencer a los lugare\u00f1os de que las luces que los atacaban eran alucinaciones colectivas y que lo que ellos hab\u00edan visto no hab\u00eda ocurrido nunca\u201d.<\/em><\/strong><\/p>\n<p>Tiempo despu\u00e9s de hacer estas pol\u00e9micas declaraciones, Hollanda fue encontrado ahorcado en la habitaci\u00f3n de su casa en Cabo Fr\u00edo. Muchos sospechan que fue \u201csilenciado\u201d, otros que sufr\u00eda de una gran depresi\u00f3n por la campa\u00f1a en su contra, lo que lo llev\u00f3 a quitarse la vida.<\/p>\n<h4>Los extra\u00f1os sucesos de la isla Colares siguen sin encontrar explicaci\u00f3n hasta el d\u00eda de hoy, a casi cuarenta a\u00f1os de sucedidos y mientras muchos de los testigos a\u00fan viven y recuerdan claramente los hechos.<\/h4>\n<form id=\"vozme_form_e78c36cbc92336882ebc6db3bd93062a\" method=\"post\" name=\"vozme_form_e78c36cbc92336882ebc6db3bd93062a\" target=\"e78c36cbc92336882ebc6db3bd93062a\" action=\"http:\/\/vozme.com\/text2voice.php\"><input name=\"text\" type=\"hidden\" value=\"La Isla Colares. \nEn el estado brasile\u00f1o de Par\u00e1, a la altura de la desembocadura del Amazonas, se encuentra la isla Colares.\u00a0 En este lugar, hasta entonces casi an\u00f3nimo, se produjeron en el a\u00f1o 1977 una serie de sucesos que a\u00fan no tienen explicaci\u00f3n.\nSus habitantes comenzaron a reportar una abundante cantidad de avistamientos de ovnis de todo tipo, luces esf\u00e9ricas, conos luminosos, platillos y cilindros atemorizantes.\u00a0 No hubiera sido diferente de otros casos mundiales, si no fuera porque los aterrorizados pobladores relataban que estas naves luminosas se aparec\u00edan sorpresivamente y les lanzaban una especie de rayo de luz que, de acuerdo a los testigos, les succionaba la sangre o al menos daba esa sensaci\u00f3n.\u00a0 As\u00ed fue que a este desagradable fen\u00f3meno se lo empez\u00f3 a llamar \u201cchupa-chupa\u201d.\nEl caso pas\u00f3 a mayores, puesto que las luces continuaron fastidiando durante muchos meses a la gente, sigui\u00e9ndolos incluso hasta dentro de sus propias viviendas lleg\u00e1ndose a conocer reportes de luces que los \u201cvisitaban\u201d por las madrugadas,\u00a0atravesando\u00a0sus techos e iluminando partes de sus cuerpos, causando ardor o quemaduras en las zonas que ten\u00edan contacto con esas luces. Se las vio tambi\u00e9n en la iglesia del pueblo, que era el lugar donde la mayor\u00eda hu\u00eda creyendo que iban a encontrar un poco de paz.\u00a0\u00a0 Muchas de las v\u00edctimas relataron que al entrar en contacto con su piel desnuda pod\u00edan\u00a0sentir como sus cuerpos se paralizaban y empezaban a sentir quemaduras en las zonas iluminadas.\nUna de las personas que le toc\u00f3 vivir la tragedia fue la joven m\u00e9dica brasile\u00f1a Wellaide Cecim Carvalho, quien se dedic\u00f3 a atender a los numerosos pacientes que llegaban con quemaduras en su cuello o pecho.\nLa Dra. Wellaide recuerda haber atendido a unos 35 o 40 pacientes aunque los damnificados fueron m\u00e1s de 80 a lo largo de casi un a\u00f1o, incluso con dos muertos adjudicados al fen\u00f3meno. \u00a0De acuerdo a la m\u00e9dica, los pacientes presentaban sensaci\u00f3n de debilidad al punto que les resultaba dif\u00edcil caminar. Los testigos adem\u00e1s ten\u00edan quemaduras con necrosis tan solo minutos despu\u00e9s de haber sufrido un ataque por un OVNI, siendo que la necrosis en quemaduras normales se produce unas 90 horas despu\u00e9s de efectuada la acci\u00f3n.\n[caption id=&quot;attachment_6954&quot; align=&quot;alignleft&quot; width=&quot;175&quot;] Doctora Carvalho[\/caption]\nLas v\u00edctimas presentaban adem\u00e1s, unas peque\u00f1as incisiones, con la sensaci\u00f3n de picaduras de viruela o peque\u00f1os agujeritos tipo inyecci\u00f3n, en los sectores quemados. Asimismo, los hemogramas de los pacientes mostraban que \u00e9stos ten\u00edan una fuerte disminuci\u00f3n de los eritrocitos y hemoglobina, es decir, anemia. Wellaide tambi\u00e9n relat\u00f3 un avistamiento que tuvo ella, de un objeto met\u00e1lico en forma de cono truncado que se pase\u00f3 por el centro del pueblo a muy baja altura un d\u00eda a mediatarde, luego de atacar a una se\u00f1ora que qued\u00f3 desvanecida. . Recuerda adem\u00e1s, que dentro del aparato volador, pod\u00edan verse dos seres\u00a0peque\u00f1os, de poco m\u00e1s de un metro de altura.\nDe acuerdo a la doctora Wellaide, dos de los pacientes que ella atendi\u00f3 murieron por causa de estos ataques, aunque se declar\u00f3 que el deceso fue por causas desconocidas.\nLo que ocurri\u00f3 despu\u00e9s fue que la Fuerza A\u00e9rea, presionada ante la dram\u00e1tica situaci\u00f3n que se estaba viviendo en Colares, se vio obligada a actuar. De esa manera se inici\u00f3 la \u201cOperaci\u00f3n Prato\u201d (platillo en portugu\u00e9s). Un grupo de militares se dedico a investigar que estaba sucediendo en Colares y sus alrededores. Sin embargo, llegaron 90 d\u00edas despu\u00e9s del cl\u00edmax de la tragedia, cuando Colares ya estaba siendo \u00a0abandonado por casi todos sus asustados habitantes.\n[caption id=&quot;attachment_6951&quot; align=&quot;alignleft&quot; width=&quot;300&quot;] Dibujos de los testigos[\/caption]\n\nDesde el punto de vista oficial, en mayo del 2004, o sea 27 a\u00f1os mas tarde, se realiz\u00f3 una reuni\u00f3n entre varios generales de alto rango de la Fuerza A\u00e9rea Brasile\u00f1a con varios uf\u00f3logos brasile\u00f1os. Los militares hicieron entrega de algunos archivos recopilados durante el transcurso de la \u201cOperaci\u00f3n Prato\u201d, para disposici\u00f3n y an\u00e1lisis de los uf\u00f3logos. Conforme con los documentos liberados, en 1977 los militares hab\u00edan tomado fotos de los OVNIs, entrevistaron a muchos testigos y tuvieron encuentros cercanos, logrando hacer dibujos de los objetos y de sus trayectorias.\nEl comandante del grupo de estudio era un militar, que era inicialmente esc\u00e9ptico, y pretend\u00eda desmitificar el asunto y explicarlo de manera l\u00f3gica como psicosis colectiva.\u00a0 Sin embargo, su opini\u00f3n fue cambiando hasta darse cuenta que algo grave hab\u00eda ocurrido en el lugar. Se trataba del Coronel Uyrange Hollanda Lima. De acuerdo a una entrevista realizada a Hollanda, los lugare\u00f1os frecuentemente les disparaban a los OVNIs. En palabras de Hollanda: \u201cSiempre les dec\u00edamos: no les disparen, no les disparen. Una vez, una fuerte luz hab\u00eda sido apuntada a un carpintero. El hombre ten\u00eda unos 50 o 60 a\u00f1os. Tom\u00f3 su rifle y le dispar\u00f3 al platillo volador. La luz lo rode\u00f3, y \u00e9l cay\u00f3 al suelo, casi paralizado. Durante 15 d\u00edas el carpintero apenas se pudo mover. Pod\u00eda hablar y escuchar pero le resultaba dif\u00edcil moverse\u201d.\nLos \u00faltimos relatos del coronel consistieron en decir que \u00e9l, junto con un compa\u00f1ero, hab\u00eda tenido tambi\u00e9n un fugaz contacto con uno de los tripulantes de los OVNIs. Seg\u00fan relat\u00f3, el tripulante baj\u00f3 de su nave y se puso delante de los dos militares, los mir\u00f3 en silencio a los ojos, y luego retorn\u00f3 a su nave a\u00e9rea. Hollanda menciona que cuando hizo el reporte militar acerca de este contacto con el ser humanoide, la Fuerza A\u00e9rea Brasile\u00f1a, dio por terminada inmediatamente la Operaci\u00f3n Prato, y guard\u00f3 los archivos de la operaci\u00f3n iniciando un prolongado silencio oficial. Las declaraciones de Hollanda le ocasionaron un enorme descr\u00e9dito y una dura campa\u00f1a en su contra.\n[caption id=&quot;attachment_6956&quot; align=&quot;alignleft&quot; width=&quot;300&quot;] Vecina luego de un ataque[\/caption]\n\nDe hecho, la misma Dra. Wellaide relata haber recibido presiones por parte de los militares: \u201cFui obligada por la Fuerza A\u00e9rea Brasile\u00f1a a convencer a los lugare\u00f1os de que las luces que los atacaban eran alucinaciones colectivas y que lo que ellos hab\u00edan visto no hab\u00eda ocurrido nunca\u201d.\nTiempo despu\u00e9s de hacer estas pol\u00e9micas declaraciones, Hollanda fue encontrado ahorcado en la habitaci\u00f3n de su casa en Cabo Fr\u00edo. Muchos sospechan que fue \u201csilenciado\u201d, otros que sufr\u00eda de una gran depresi\u00f3n por la campa\u00f1a en su contra, lo que lo llev\u00f3 a quitarse la vida.\nLos extra\u00f1os sucesos de la isla Colares siguen sin encontrar explicaci\u00f3n hasta el d\u00eda de hoy, a casi cuarenta a\u00f1os de sucedidos y mientras muchos de los testigos a\u00fan viven y recuerdan claramente los hechos.\n\" \/><input name=\"lang\" type=\"hidden\" value=\"es\" \/><input name=\"gn\" type=\"hidden\" value=\"ml\" \/><input type=\"hidden\" id=\"interface\" name=\"interface\" value=\"full\" \/>\n\t\t\t<div style=\"text-align:left;\">\n\t\t\t\n\t\t\t\t<input style=\"float:left;\" type=\"image\" width=\"40\" height=\"40\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/plugins\/vozme\/img\/megaphone40x40w.gif\" alt=\"Escucha este post\" onclick=\"window.open('', 'e78c36cbc92336882ebc6db3bd93062a', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes');\">\n\t\t\t\t<div style=\"margin-left:48px; text-align:left;\"><a style=\"font-size:12px;\" href=\"javascript:void(0);\" onclick=\"window.open('', 'e78c36cbc92336882ebc6db3bd93062a', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes'); document.getElementById('vozme_form_e78c36cbc92336882ebc6db3bd93062a').submit();\">Escucha<br\/>este post<\/a><\/div>\n\t\t\t<\/div><\/form>","protected":false},"excerpt":{"rendered":"<p>En el estado brasile\u00f1o de Par\u00e1, a la altura de la desembocadura del Amazonas, se encuentra la isla Colares.\u00a0 En este lugar, hasta entonces casi an\u00f3nimo, se produjeron en el a\u00f1o 1977 una serie de sucesos que a\u00fan no tienen explicaci\u00f3n. Sus habitantes comenzaron a reportar una abundante cantidad de avistamientos de ovnis de todo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":6957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,3,5,1],"tags":[60,61,4],"class_list":["post-6947","post","type-post","status-publish","format-standard","has-post-thumbnail","category-fenomenos","category-misterios","category-rarezas-2","category-sin-categoria","tag-isla","tag-misterio","tag-ovni","czr-hentry"],"_links":{"self":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/6947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/comments?post=6947"}],"version-history":[{"count":0,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/6947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media\/6957"}],"wp:attachment":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media?parent=6947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/categories?post=6947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/tags?post=6947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}