{"id":9756,"date":"2018-02-27T23:25:10","date_gmt":"2018-02-27T23:25:10","guid":{"rendered":"http:\/\/ojoscuriosos.com\/?p=9756"},"modified":"2018-02-27T23:25:10","modified_gmt":"2018-02-27T23:25:10","slug":"lo-sabias-113","status":"publish","type":"post","link":"https:\/\/megatandil.com.ar\/ojoscuriosos\/lo-sabias-113\/","title":{"rendered":"Lo Sab\u00edas?"},"content":{"rendered":"<h2><span style=\"color: #008080;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-9757\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/128293038324544.jpg\" alt=\"\" width=\"445\" height=\"285\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/128293038324544.jpg 445w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/128293038324544-300x192.jpg 300w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-9759\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/o_1346070938.jpg\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/o_1346070938.jpg 640w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/o_1346070938-300x169.jpg 300w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/o_1346070938-528x297.jpg 528w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>En 1918, un joven m\u00e9dico argentino, otorrinolaring\u00f3logo, llamado Enrique Tel\u00e9maco Susini, viaj\u00f3 a Francia para estudiar el efecto de los gases asfixiantes sobre las vias respiratorias, arma nefasta que se hab\u00eda utilizado en la Primera Guerra Mundial.\u00a0\u00a0 <\/span><\/h2>\n<p><span style=\"color: #000000;\">Y fue en Francia donde por casualidad encontr\u00f3 tirados en un laboratorio, unos viejos equipos de radio con transmisores abandonados, l\u00e1mparas y v\u00e1lvulas en buen estado.\u00a0 Les llam\u00f3 la atenci\u00f3n y las trajo a Argentina ocultas en un abrigo con la loca idea de divertirse un poco. No sab\u00eda muy bien para qu\u00e9 serv\u00edan y se imagin\u00f3 alguna broma con sus tres amigos, <strong>C\u00e9sar Guerrico, Luis Romero Carranza y Miguel Mujica<\/strong>, ninguno mayor de 25 a\u00f1os. Solo imagin\u00f3 una travesura.<\/span><\/p>\n<p><span style=\"color: #000000;\">Rearmando esos vetustos equipos, el d\u00eda <strong>27 de agosto de 1920<\/strong>, minutos despu\u00e9s de las nueve de la noche, transmitieron desde el teatro Coliseo la \u00f3pera \u00abParsifal\u00bb, mediante la onda que emit\u00eda una antena casera ubicada en los altos de un edificio ubicado en Cerrito y Charcas, en Buenos Aires, por lo que fueron conocidos como \u00ablos locos de la azotea\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">La voz del propio Susini abri\u00f3 esa transmisi\u00f3n de tres horas, que pudieron oir solo un pu\u00f1ado de personas, ya que eran unos pocos pudientes los que\u00a0 ten\u00edan receptores a modo de snobismo. La radio no exist\u00eda como entretenimiento y esa fue la primera transmisi\u00f3n mundial de un programa completo.\u00a0 Dado el impacto internacional, la bautizaron como Radio Argentina y puso a la Argentina a la vanguardia de una t\u00e9cnica que sigue vigente hasta el dia de hoy: Programas de larga duraci\u00f3n con un formato determinado. \u00a0Argentina fue el primer pa\u00eds en emitir un programa de radio.<\/span><\/p>\n<p><span style=\"color: #000000;\">Si no hubiese sido por los efectos de los gases asfixiantes que fue a estudiar a Francia, dif\u00edcilmente Susini se hubiese topado con los viejos elementos radiof\u00f3nicos que lo llevaron a ser un pionero en el mundo.\u00a0 Gases y ondas se mezclaron por los caprichos del destino.<img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-9758\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/los-locos-de-la-azotea.jpg\" alt=\"\" width=\"468\" height=\"354\" srcset=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/los-locos-de-la-azotea.jpg 468w, https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/uploads\/2018\/02\/los-locos-de-la-azotea-300x227.jpg 300w\" sizes=\"auto, (max-width: 468px) 100vw, 468px\" \/><\/span><\/p>\n<form id=\"vozme_form_16d9029c1dc90fc1fd10c0304256de4b\" method=\"post\" name=\"vozme_form_16d9029c1dc90fc1fd10c0304256de4b\" target=\"16d9029c1dc90fc1fd10c0304256de4b\" action=\"http:\/\/vozme.com\/text2voice.php\"><input name=\"text\" type=\"hidden\" value=\"Lo Sab\u00edas?.  En 1918, un joven m\u00e9dico argentino, otorrinolaring\u00f3logo, llamado Enrique Tel\u00e9maco Susini, viaj\u00f3 a Francia para estudiar el efecto de los gases asfixiantes sobre las vias respiratorias, arma nefasta que se hab\u00eda utilizado en la Primera Guerra Mundial.\u00a0\u00a0 \nY fue en Francia donde por casualidad encontr\u00f3 tirados en un laboratorio, unos viejos equipos de radio con transmisores abandonados, l\u00e1mparas y v\u00e1lvulas en buen estado.\u00a0 Les llam\u00f3 la atenci\u00f3n y las trajo a Argentina ocultas en un abrigo con la loca idea de divertirse un poco. No sab\u00eda muy bien para qu\u00e9 serv\u00edan y se imagin\u00f3 alguna broma con sus tres amigos, C\u00e9sar Guerrico, Luis Romero Carranza y Miguel Mujica, ninguno mayor de 25 a\u00f1os. Solo imagin\u00f3 una travesura.\nRearmando esos vetustos equipos, el d\u00eda 27 de agosto de 1920, minutos despu\u00e9s de las nueve de la noche, transmitieron desde el teatro Coliseo la \u00f3pera \u00abParsifal\u00bb, mediante la onda que emit\u00eda una antena casera ubicada en los altos de un edificio ubicado en Cerrito y Charcas, en Buenos Aires, por lo que fueron conocidos como \u00ablos locos de la azotea\u00bb.\nLa voz del propio Susini abri\u00f3 esa transmisi\u00f3n de tres horas, que pudieron oir solo un pu\u00f1ado de personas, ya que eran unos pocos pudientes los que\u00a0 ten\u00edan receptores a modo de snobismo. La radio no exist\u00eda como entretenimiento y esa fue la primera transmisi\u00f3n mundial de un programa completo.\u00a0 Dado el impacto internacional, la bautizaron como Radio Argentina y puso a la Argentina a la vanguardia de una t\u00e9cnica que sigue vigente hasta el dia de hoy: Programas de larga duraci\u00f3n con un formato determinado. \u00a0Argentina fue el primer pa\u00eds en emitir un programa de radio.\nSi no hubiese sido por los efectos de los gases asfixiantes que fue a estudiar a Francia, dif\u00edcilmente Susini se hubiese topado con los viejos elementos radiof\u00f3nicos que lo llevaron a ser un pionero en el mundo.\u00a0 Gases y ondas se mezclaron por los caprichos del destino.\n\" \/><input name=\"lang\" type=\"hidden\" value=\"es\" \/><input name=\"gn\" type=\"hidden\" value=\"ml\" \/><input type=\"hidden\" id=\"interface\" name=\"interface\" value=\"full\" \/>\n\t\t\t<div style=\"text-align:left;\">\n\t\t\t\n\t\t\t\t<input style=\"float:left;\" type=\"image\" width=\"40\" height=\"40\" src=\"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-content\/plugins\/vozme\/img\/megaphone40x40w.gif\" alt=\"Escucha este post\" onclick=\"window.open('', '16d9029c1dc90fc1fd10c0304256de4b', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes');\">\n\t\t\t\t<div style=\"margin-left:48px; text-align:left;\"><a style=\"font-size:12px;\" href=\"javascript:void(0);\" onclick=\"window.open('', '16d9029c1dc90fc1fd10c0304256de4b', 'width=600,height=370,scrollbars=yes,location=yes,menubar=yes,resizable=yes,status=yes,toolbar=yes'); document.getElementById('vozme_form_16d9029c1dc90fc1fd10c0304256de4b').submit();\">Escucha<br\/>este post<\/a><\/div>\n\t\t\t<\/div><\/form>","protected":false},"excerpt":{"rendered":"<p>En 1918, un joven m\u00e9dico argentino, otorrinolaring\u00f3logo, llamado Enrique Tel\u00e9maco Susini, viaj\u00f3 a Francia para estudiar el efecto de los gases asfixiantes sobre las vias respiratorias, arma nefasta que se hab\u00eda utilizado en la Primera Guerra Mundial.\u00a0\u00a0 Y fue en Francia donde por casualidad encontr\u00f3 tirados en un laboratorio, unos viejos equipos de radio con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9756","post","type-post","status-publish","format-standard","has-post-thumbnail","category-lo-sabias","czr-hentry"],"_links":{"self":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/9756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/comments?post=9756"}],"version-history":[{"count":0,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/posts\/9756\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media\/9759"}],"wp:attachment":[{"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/media?parent=9756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/categories?post=9756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatandil.com.ar\/ojoscuriosos\/wp-json\/wp\/v2\/tags?post=9756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}